{"id":6567,"date":"2018-09-04T08:57:35","date_gmt":"2018-09-04T06:57:35","guid":{"rendered":"https:\/\/www.checchiemagli.com\/testimonial\/vincenzo-ritrovati-teramo-te\/"},"modified":"2018-09-04T08:57:35","modified_gmt":"2018-09-04T06:57:35","slug":"vincenzo-ritrovati-teramo-te","status":"publish","type":"testimonial","link":"https:\/\/www.checchiemagli.com\/fr\/testimonial\/vincenzo-ritrovati-teramo-te\/","title":{"rendered":"VINCENZO RITROVATI \u2013 Teramo (TE)"},"content":{"rendered":"<div id=\"content_body\">\n<div id=\"columndx-g\">\n<div>\n<p>Una grande diversit\u00e0 di specie orticole estive ed invernali che si alternano nel corso dell\u2019anno. E\u2019 questa la caratteristica principale della\u00a0<strong>Soc. Agricola Punto Verde<\/strong>\u00a0a Teramo, sulla costa abruzzese.<\/p>\n<p>Oltre a colture tradizionali quali mais, frumenti ed erba medica, l\u2019azienda ha destinato, infatti, una parte della superficie coltivata all\u2019orticoltura, con l\u2019obiettivo di rifornire tutto l\u2019anno lo spaccio aziendale, i mercatini rionali e qualche distributore locale.\u201cColtiviamo numerose specie di orticole, afferma il titolare\u00a0<strong>Vincenzo Ritrovati<\/strong>, destinando piccole superfici alle singole variet\u00e0, in modo da offrire ai nostri clienti il massimo assortimento possibile\u201d.<\/p>\n<p>Cliente Checchi &amp; Magli da oltre 20 anni, l\u2019azienda nel tempo ha ampliato la propria attivit\u00e0, decidendo cos\u00ec di acquistare quest\u2019anno due nuove attrezzature, una trapiantatrice\u00a0<strong>Wolf a 1 fila<\/strong>e la pacciamatrice\u00a0<strong>PS 14<\/strong>\u00a0\u00a0dotata di segnafile, microgranulatore e spandiconcime e kit di posa manichetta d\u2019irrigazione.<\/p>\n<p>\u201cEro innamorato di queste macchine, racconta Vincenzo, e andavo sempre a vederle alle fiere; alla fine ho deciso di fare questo investimento, in modo da rendere l\u2019azienda completamente autonoma in termini di meccanizzazione.\u201dOggi per la Soc. Agricola Punto Verde l\u2019orticoltura \u00e8, infatti, un settore sempre pi\u00f9 importante e quasi tutto viene trapiantato a macchina.<\/p>\n<p>\u201cLe Checchi &amp; Magli sono attrezzature concepite e costruite al meglio con una qualit\u00e0 di lavoro altissima, spiega \u00a0Vincenzo, e soprattutto offrono la possibilit\u00e0 di staccare i diversi componenti e di combinarli anche con le altre trapiantatrici Checchi &amp; Magli, in base alle necessit\u00e0\u201d.<\/p>\n<p>\u201cQuando ho visto per la prima volta la PS 14 acquistata allestita con tutti gli accessori, conclude Vincenzo, confesso che mi sono spaventato, pensando che gli ingombri fossero eccessivi per i piccoli appezzamenti della mia azienda.<\/p>\n<p>Alla fine ho dovuto ricredermi: \u00e8 un\u2019attrezzatura molto maneggevole, dove puoi montare e smontare con grande facilit\u00e0 quello che serve di volta in volta, oltre ad essere davvero semplice da utilizzare\u201d.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"content_footer\">\n<div id=\"footer_container\">\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una grande diversit\u00e0 di specie orticole estive ed invernali che si alternano nel corso dell\u2019anno. E\u2019 questa la caratteristica principale della\u00a0Soc. Agricola Punto Verde\u00a0a Teramo, sulla costa abruzzese. Oltre a colture tradizionali quali mais, frumenti ed erba medica, l\u2019azienda ha destinato, infatti, una parte della superficie coltivata all\u2019orticoltura, con l\u2019obiettivo di rifornire tutto l\u2019anno lo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3816,"menu_order":3,"template":"","format":"standard","meta":{"_acf_changed":false,"_gspb_post_css":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-6567","testimonial","type-testimonial","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VINCENZO RITROVATI \u2013 Teramo (TE) - Checchi e Magli<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VINCENZO RITROVATI \u2013 Teramo (TE) - Checchi e Magli\" \/>\n<meta property=\"og:description\" content=\"Una grande diversit\u00e0 di specie orticole estive ed invernali che si alternano nel corso dell\u2019anno. E\u2019 questa la caratteristica principale della\u00a0Soc. Agricola Punto Verde\u00a0a Teramo, sulla costa abruzzese. Oltre a colture tradizionali quali mais, frumenti ed erba medica, l\u2019azienda ha destinato, infatti, una parte della superficie coltivata all\u2019orticoltura, con l\u2019obiettivo di rifornire tutto l\u2019anno lo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.checchiemagli.com\/fr\/testimonial\/vincenzo-ritrovati-teramo-te\/\" \/>\n<meta property=\"og:site_name\" content=\"Checchi e Magli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/checchiemagli\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.checchiemagli.com\/wp-content\/uploads\/2025\/04\/test_teramo2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"284\" \/>\n\t<meta property=\"og:image:height\" content=\"213\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@checchiemagli\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VINCENZO RITROVATI \u2013 Teramo (TE) - Checchi e Magli","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"VINCENZO RITROVATI \u2013 Teramo (TE) - Checchi e Magli","og_description":"Una grande diversit\u00e0 di specie orticole estive ed invernali che si alternano nel corso dell\u2019anno. E\u2019 questa la caratteristica principale della\u00a0Soc. Agricola Punto Verde\u00a0a Teramo, sulla costa abruzzese. Oltre a colture tradizionali quali mais, frumenti ed erba medica, l\u2019azienda ha destinato, infatti, una parte della superficie coltivata all\u2019orticoltura, con l\u2019obiettivo di rifornire tutto l\u2019anno lo...","og_url":"https:\/\/www.checchiemagli.com\/fr\/testimonial\/vincenzo-ritrovati-teramo-te\/","og_site_name":"Checchi e Magli","article_publisher":"https:\/\/www.facebook.com\/checchiemagli\/","og_image":[{"width":284,"height":213,"url":"https:\/\/www.checchiemagli.com\/wp-content\/uploads\/2025\/04\/test_teramo2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@checchiemagli","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.checchiemagli.com\/fr\/testimonial\/vincenzo-ritrovati-teramo-te\/","url":"https:\/\/www.checchiemagli.com\/fr\/testimonial\/vincenzo-ritrovati-teramo-te\/","name":"VINCENZO RITROVATI \u2013 Teramo (TE) - Checchi e Magli","isPartOf":{"@id":"https:\/\/www.checchiemagli.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.checchiemagli.com\/fr\/testimonial\/vincenzo-ritrovati-teramo-te\/#primaryimage"},"image":{"@id":"https:\/\/www.checchiemagli.com\/fr\/testimonial\/vincenzo-ritrovati-teramo-te\/#primaryimage"},"thumbnailUrl":"https:\/\/www.checchiemagli.com\/wp-content\/uploads\/2025\/04\/test_teramo2.jpg","datePublished":"2018-09-04T06:57:35+00:00","breadcrumb":{"@id":"https:\/\/www.checchiemagli.com\/fr\/testimonial\/vincenzo-ritrovati-teramo-te\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.checchiemagli.com\/fr\/testimonial\/vincenzo-ritrovati-teramo-te\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.checchiemagli.com\/fr\/testimonial\/vincenzo-ritrovati-teramo-te\/#primaryimage","url":"https:\/\/www.checchiemagli.com\/wp-content\/uploads\/2025\/04\/test_teramo2.jpg","contentUrl":"https:\/\/www.checchiemagli.com\/wp-content\/uploads\/2025\/04\/test_teramo2.jpg","width":284,"height":213},{"@type":"BreadcrumbList","@id":"https:\/\/www.checchiemagli.com\/fr\/testimonial\/vincenzo-ritrovati-teramo-te\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.checchiemagli.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Testimonial","item":"https:\/\/www.checchiemagli.com\/fr\/testimonial\/"},{"@type":"ListItem","position":3,"name":"VINCENZO RITROVATI \u2013 Teramo (TE)"}]},{"@type":"WebSite","@id":"https:\/\/www.checchiemagli.com\/fr\/#website","url":"https:\/\/www.checchiemagli.com\/fr\/","name":"Checchi&Magli","description":"Produzione e Distribuzione di Macchine Agricole","publisher":{"@id":"https:\/\/www.checchiemagli.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.checchiemagli.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.checchiemagli.com\/fr\/#organization","name":"Checchi&Magli","url":"https:\/\/www.checchiemagli.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.checchiemagli.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.checchiemagli.com\/wp-content\/uploads\/2025\/03\/logo.png","contentUrl":"https:\/\/www.checchiemagli.com\/wp-content\/uploads\/2025\/03\/logo.png","width":633,"height":149,"caption":"Checchi&Magli"},"image":{"@id":"https:\/\/www.checchiemagli.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/checchiemagli\/","https:\/\/x.com\/checchiemagli","https:\/\/www.youtube.com\/user\/checchiemagli","https:\/\/www.instagram.com\/checchiemagli\/","https:\/\/www.linkedin.com\/company\/checchiemagli\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.checchiemagli.com\/fr\/wp-json\/wp\/v2\/testimonial\/6567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.checchiemagli.com\/fr\/wp-json\/wp\/v2\/testimonial"}],"about":[{"href":"https:\/\/www.checchiemagli.com\/fr\/wp-json\/wp\/v2\/types\/testimonial"}],"author":[{"embeddable":true,"href":"https:\/\/www.checchiemagli.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.checchiemagli.com\/fr\/wp-json\/wp\/v2\/testimonial\/6567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.checchiemagli.com\/fr\/wp-json\/wp\/v2\/media\/3816"}],"wp:attachment":[{"href":"https:\/\/www.checchiemagli.com\/fr\/wp-json\/wp\/v2\/media?parent=6567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}